{"id":98423,"date":"2026-04-18T00:32:39","date_gmt":"2026-04-17T16:32:39","guid":{"rendered":"https:\/\/hsimc.hfa.edu.ph\/website\/?p=98423"},"modified":"2026-03-19T09:46:03","modified_gmt":"2026-03-19T01:46:03","slug":"juega-gratis-contra-ia-o-2-jugadores-optimizado-2","status":"publish","type":"post","link":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/","title":{"rendered":"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil"},"content":{"rendered":"<div id=\"toc\" style=\"background: #f9f9f9;border: 1px solid #aaa;display: table;margin-bottom: 1em;padding: 1em;width: 350px;\">\n<p class=\"toctitle\" style=\"font-weight: 700;text-align: center;\">Content<\/p>\n<ul class=\"toc_list\">\n<li><a href=\"#toc-0\">Juegos de empat\u00eda para trabajar en el aula con ni\u00f1os<\/a><\/li>\n<li><a href=\"#toc-2\">Ventajas de jugar al tres en raya<\/a><\/li>\n<li><a href=\"#toc-3\">Estrategia: \u00bfc\u00f3mo jugar al tres en raya?<\/a><\/li>\n<li><a href=\"#toc-5\">F\u00fatbol de Papel<\/a><\/li>\n<\/ul>\n<\/div>\n<p>El algoritmo de inteligencia artificial (IA) m\u00e1s com\u00fan, minimax, se puede usar para jugar al meta tres en raya , pero es dif\u00edcil de implementar. Pieza de est\u00e9tica rustica por su base en madera natural con el toque divertido de sus fichas de colores. Cada tablero del tres en raya se realiza mediante un proceso artesanal,, por lo que cada unidad de este juego es \u00fanica y diferente.<\/p>\n<h2 id=\"toc-0\">Juegos de empat\u00eda para trabajar en el aula con ni\u00f1os<\/h2>\n<p>El Tres en Raya es un juego fascinante para todas las edades. Descubrir\u00e1s las estrategias exitosas y las reglas del juego. El Tres en Raya es un juego de tablero cl\u00e1sico que se juega en una cuadr\u00edcula de 3&#215;3. En caso de que el jugador haga trampa el ganador ser\u00e1 el otro.<\/p>\n<p>Controlar el centro incrementa considerablemente tus posibilidades de ganar. Los juegos de mesa surgieron en el Neol\u00edtico y fueron evolucionando en la Edad de Bronce. En poco tiempo se convirti\u00f3 en uno de los juegos m\u00e1s populares de las clases bajas en la Edad Media.<\/p>\n<h3 id=\"toc-1\">Tres en Raya en un Campo M\u00e1s Grande: 4 o 5 en L\u00ednea<\/h3>\n<p>Como ya hemos dicho antes, se puede dibujar sobre un papel un cuadrado con 9 casillas y que cada jugador vaya rellenado las casillas. Pero para no gastar tanto papel, lo ideal ser\u00eda hacerte un tablero y 5 fichas de cada s\u00edmbolo que pudiera reutilizarse. \u00bfQui\u00e9n no se ha puesto a jugar tres en raya alguna vez para combatir el aburrimiento? En nuestros tiempos, es usual jugar con l\u00e1piz y papel y, en la actualidad, en plena era de Internet, tambi\u00e9n en modo online. Es casi imposible que el segundo jugador gane a menos que el primero cometa un error. A continuaci\u00f3n, seleccione el formato de la cuadr\u00edcula.<\/p>\n<h3 id=\"toc-2\">Ventajas de jugar al tres en raya<\/h3>\n<p>El objetivo del juego es ir moviendo por turnos una a una las fichas sobre el tablero hasta realizar un tres en raya antes que el otro jugador. Ideal para jugar en familia y con ni\u00f1os a partir de 10 a\u00f1os. Preparaci\u00f3n del juego instant\u00e1nea y duraci\u00f3n de las partidas entre 3 y 5 minutos.<\/p>\n<ul>\n<li>Los juegos de Tres En Raya son divertidos y gratificantes, con una mezcla perfecta de estrategia y simplicidad.<\/li>\n<li>Tu oponente solo puede bloquear uno de ellos, permiti\u00e9ndote ganar en el siguiente turno.<\/li>\n<li>Pero al menos aumentar\u00e1s con claridad tus posibilidades de ganar incluso cuando te encuentres en el puesto de segundo jugador.<\/li>\n<li>Cada movimiento de un jugador en uno de los peque\u00f1os campos dicta en qu\u00e9 sector el siguiente jugador debe hacer su movimiento.<\/li>\n<\/ul>\n<p>Toma el medio si el primer jugador coloca su s\u00edmbolo en una esquina. <a href=\"3enraya.es\">3enraya.es<\/a> \u00a1Juega al tradicional Tres en Raya online aqu\u00ed en Juegos Area! Desaf\u00eda a tus amigos o juega solo en el ordenador o m\u00f3vil.<\/p>\n<p>El juego m\u00e1s de moda en la red ha llegado a nuestra web para que puedas disfrutarlo. Se trata del Higher or Lower Game, que en espa\u00f1ol ha sido traducido de muchas formas. Tu oponente solo puede bloquear uno de ellos, permiti\u00e9ndote ganar en el siguiente turno.<\/p>\n<h2 id=\"toc-5\">F\u00fatbol de Papel<\/h2>\n<p>Los jugadores se turnan para hacer movimientos sin saltarse. Los juegos Tres en Raya se juegan en tableros como los dibujados. Nuestra versi\u00f3n permite partidas de Tres en Raya para 2 jugadores o jugar en solitario contra la IA. En estas variantes especiales, el objetivo es formar una l\u00ednea con cuatro marcas en lugar de tres. Si nadie lo consigue y el tablero queda lleno, el juego termina en empate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Content Juegos de empat\u00eda para trabajar en el aula con ni\u00f1os Ventajas de jugar al tres en raya Estrategia: \u00bfc\u00f3mo jugar al tres en raya? F\u00fatbol de Papel El algoritmo de inteligencia artificial (IA) m\u00e1s com\u00fan, minimax, se puede usar para jugar al meta tres en raya , pero es dif\u00edcil de implementar. Pieza de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[432],"tags":[],"class_list":["post-98423","post","type-post","status-publish","format-standard","hentry","category-3enraya-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil - Holy Family Academy Instructional Media Center High School Department<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil - Holy Family Academy Instructional Media Center High School Department\" \/>\n<meta property=\"og:description\" content=\"Content Juegos de empat\u00eda para trabajar en el aula con ni\u00f1os Ventajas de jugar al tres en raya Estrategia: \u00bfc\u00f3mo jugar al tres en raya? F\u00fatbol de Papel El algoritmo de inteligencia artificial (IA) m\u00e1s com\u00fan, minimax, se puede usar para jugar al meta tres en raya , pero es dif\u00edcil de implementar. Pieza de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Holy Family Academy Instructional Media Center High School Department\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AskLIMCA\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T16:32:39+00:00\" \/>\n<meta name=\"author\" content=\"Librarian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Librarian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/\"},\"author\":{\"name\":\"Librarian\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#\\\/schema\\\/person\\\/cdc648424e94eb59d167e9ef51d515e8\"},\"headline\":\"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil\",\"datePublished\":\"2026-04-17T16:32:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/\"},\"wordCount\":659,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#organization\"},\"articleSection\":[\"3enraya.es\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/\",\"url\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/\",\"name\":\"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil - Holy Family Academy Instructional Media Center High School Department\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#website\"},\"datePublished\":\"2026-04-17T16:32:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/2026\\\/04\\\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#website\",\"url\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/\",\"name\":\"Holy Family Academy High School IMC\",\"description\":\"Instructional Media Center High School Department\",\"publisher\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#organization\",\"name\":\"Holy Family Academy Instructional Media Center High School Department\",\"url\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/opac-web\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/opac-web\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo.png\",\"width\":512,\"height\":512,\"caption\":\"Holy Family Academy Instructional Media Center High School Department\"},\"image\":{\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AskLIMCA\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Holy_Family_Academy_(Philippines)\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/website\\\/#\\\/schema\\\/person\\\/cdc648424e94eb59d167e9ef51d515e8\",\"name\":\"Librarian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c250bb5562ea8d6197cb3d2d35b578e83b895e49acc06efa150071fdd97b9ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c250bb5562ea8d6197cb3d2d35b578e83b895e49acc06efa150071fdd97b9ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c250bb5562ea8d6197cb3d2d35b578e83b895e49acc06efa150071fdd97b9ba?s=96&d=mm&r=g\",\"caption\":\"Librarian\"},\"sameAs\":[\"https:\\\/\\\/hsimc.hfa.edu.ph\\\/opac-web\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil - Holy Family Academy Instructional Media Center High School Department","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/","og_locale":"en_US","og_type":"article","og_title":"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil - Holy Family Academy Instructional Media Center High School Department","og_description":"Content Juegos de empat\u00eda para trabajar en el aula con ni\u00f1os Ventajas de jugar al tres en raya Estrategia: \u00bfc\u00f3mo jugar al tres en raya? F\u00fatbol de Papel El algoritmo de inteligencia artificial (IA) m\u00e1s com\u00fan, minimax, se puede usar para jugar al meta tres en raya , pero es dif\u00edcil de implementar. Pieza de [&hellip;]","og_url":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/","og_site_name":"Holy Family Academy Instructional Media Center High School Department","article_publisher":"https:\/\/www.facebook.com\/AskLIMCA","article_published_time":"2026-04-17T16:32:39+00:00","author":"Librarian","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Librarian","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/#article","isPartOf":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/"},"author":{"name":"Librarian","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#\/schema\/person\/cdc648424e94eb59d167e9ef51d515e8"},"headline":"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil","datePublished":"2026-04-17T16:32:39+00:00","mainEntityOfPage":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/"},"wordCount":659,"commentCount":0,"publisher":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#organization"},"articleSection":["3enraya.es"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/","url":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/","name":"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil - Holy Family Academy Instructional Media Center High School Department","isPartOf":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#website"},"datePublished":"2026-04-17T16:32:39+00:00","breadcrumb":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/2026\/04\/juega-gratis-contra-ia-o-2-jugadores-optimizado-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hsimc.hfa.edu.ph\/website\/"},{"@type":"ListItem","position":2,"name":"Juega Gratis contra IA o 2 Jugadores Optimizado M\u00f3vil"}]},{"@type":"WebSite","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#website","url":"https:\/\/hsimc.hfa.edu.ph\/website\/","name":"Holy Family Academy High School IMC","description":"Instructional Media Center High School Department","publisher":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hsimc.hfa.edu.ph\/website\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#organization","name":"Holy Family Academy Instructional Media Center High School Department","url":"https:\/\/hsimc.hfa.edu.ph\/website\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#\/schema\/logo\/image\/","url":"https:\/\/hsimc.hfa.edu.ph\/opac-web\/wp-content\/uploads\/2021\/05\/logo.png","contentUrl":"https:\/\/hsimc.hfa.edu.ph\/opac-web\/wp-content\/uploads\/2021\/05\/logo.png","width":512,"height":512,"caption":"Holy Family Academy Instructional Media Center High School Department"},"image":{"@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AskLIMCA","https:\/\/en.wikipedia.org\/wiki\/Holy_Family_Academy_(Philippines)"]},{"@type":"Person","@id":"https:\/\/hsimc.hfa.edu.ph\/website\/#\/schema\/person\/cdc648424e94eb59d167e9ef51d515e8","name":"Librarian","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6c250bb5562ea8d6197cb3d2d35b578e83b895e49acc06efa150071fdd97b9ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c250bb5562ea8d6197cb3d2d35b578e83b895e49acc06efa150071fdd97b9ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c250bb5562ea8d6197cb3d2d35b578e83b895e49acc06efa150071fdd97b9ba?s=96&d=mm&r=g","caption":"Librarian"},"sameAs":["https:\/\/hsimc.hfa.edu.ph\/opac-web\/"]}]}},"_links":{"self":[{"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/posts\/98423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/comments?post=98423"}],"version-history":[{"count":1,"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/posts\/98423\/revisions"}],"predecessor-version":[{"id":98424,"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/posts\/98423\/revisions\/98424"}],"wp:attachment":[{"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/media?parent=98423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/categories?post=98423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hsimc.hfa.edu.ph\/website\/wp-json\/wp\/v2\/tags?post=98423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}